{"id":11772,"date":"2023-10-30T10:36:31","date_gmt":"2023-10-30T15:36:31","guid":{"rendered":"https:\/\/pdmc-montessori.org\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/"},"modified":"2025-06-10T21:55:03","modified_gmt":"2025-06-11T01:55:03","slug":"cours-video-sur-la-discipline-positive-dans-la-classe-montessori","status":"publish","type":"product","link":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/","title":{"rendered":"Cours vid\u00e9o sur la discipline positive dans la classe Montessori"},"content":{"rendered":"\t\t<div data-elementor-type=\"product-post\" data-elementor-id=\"11772\" class=\"elementor elementor-11772 elementor-3638\" data-elementor-post-type=\"product\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-94e8190 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"94e8190\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d4682df\" data-id=\"d4682df\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ff84e57 elementor-widget elementor-widget-video\" data-id=\"ff84e57\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;video_type&quot;:&quot;vimeo&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<iframe class=\"elementor-video-iframe\" allowfullscreen allow=\"clipboard-write\" title=\"vimeo Video Player\" src=\"https:\/\/player.vimeo.com\/video\/612898404?color&amp;autopause=0&amp;loop=0&amp;muted=0&amp;title=1&amp;portrait=1&amp;byline=1#t=\"><\/iframe>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6513349 elementor-widget elementor-widget-spacer\" data-id=\"6513349\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f499c0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f499c0\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b6d780\" data-id=\"3b6d780\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9e3b5f9 elementor-widget elementor-widget-text-editor\" data-id=\"9e3b5f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>Description du cours<\/strong><\/p><p>Le cours virtuel Discipline positive dans la classe Montessori propose une m\u00e9thode d&rsquo;encadrement des enfants bas\u00e9e sur les principes de psychologie comportementale d&rsquo;Alfred Adler et de Rudolf Driekurs. Le cours vous fournit un cadre pour l&rsquo;orientation des enfants et un ensemble d&rsquo;outils de gestion de la classe conformes \u00e0 la philosophie Montessori qui n&rsquo;est pas souvent abord\u00e9e dans les programmes de formation des enseignants Montessori. Les outils fournis permettent de cultiver des classes o\u00f9 les \u00e9l\u00e8ves r\u00e9solvent les conflits entre eux de mani\u00e8re ind\u00e9pendante, sont mieux \u00e0 m\u00eame de r\u00e9guler leurs \u00e9motions, assument la responsabilit\u00e9 de leurs actes et o\u00f9 chacun contribue au maintien d&rsquo;un environnement d&rsquo;apprentissage harmonieux.  <\/p><p>Jane Nelsen, cofondatrice de la Discipline Positive et th\u00e9rapeute conjugale et familiale agr\u00e9\u00e9e, et Chip DeLorenzo, \u00e9ducateur Montessori exp\u00e9riment\u00e9 avec 30 ans d&rsquo;exp\u00e9rience \u00e0 diff\u00e9rents postes, de guide principal \u00e0 directeur d&rsquo;\u00e9cole et facilitateur de la Discipline Positive. Cette \u00e9quipe extraordinaire propose des solutions pratiques, claires et chaleureuses, qui vous permettront de guider les enfants de mani\u00e8re respectueuse et de les aider \u00e0 ressentir un sentiment d&rsquo;appartenance et d&rsquo;importance, ce qui aura un impact positif sur leur comportement et leurs r\u00e9sultats d&rsquo;apprentissage. Chip est un ma\u00eetre conteur, et ses exp\u00e9riences dans les classes Montessori constituent la toile de fond pour comprendre et appliquer efficacement les techniques de Discipline Positive.  <\/p><p>Pr\u00e9sent\u00e9es sous forme d&rsquo;histoires m\u00e9morables et de strat\u00e9gies r\u00e9alisables, les 10 le\u00e7ons vous guident \u00e0 travers les principes sous-jacents de la discipline positive dans la classe Montessori. Avec le Playbook et le livre bonus qui l&rsquo;accompagnent, ce cours aura un impact positif sur votre relation avec chaque \u00e9l\u00e8ve et renforcera la coh\u00e9sion sociale dans votre classe et votre communaut\u00e9 scolaire. <\/p><p><strong>Mat\u00e9riel de cours<\/strong><\/p><p>Voici les \u00e9l\u00e9ments dont vous aurez besoin pour participer \u00e0 l&rsquo;atelier :<\/p><ul><li>Un appareil (ordinateur, tablette ou t\u00e9l\u00e9phone intelligent) avec un logiciel de navigation \u00e0 jour<\/li><li>Une connexion Internet permettant de regarder des vid\u00e9os (par exemple YouTube)<\/li><li>Haut-parleurs ou \u00e9couteurs<\/li><li>La possibilit\u00e9 de t\u00e9l\u00e9charger et d&rsquo;imprimer un Playbook .pdf<br>(un lien est disponible dans votre email de confirmation d&rsquo;achat ou dans la premi\u00e8re le\u00e7on).<\/li><\/ul><p><strong>Contenu du cours<\/strong><\/p><p>Chapitre 1 &#8211; Introduction<\/p><ul><li>1.1 Introduction<\/li><li>1.2 Principes d&rsquo;une discipline efficace<\/li><li>1.3 Deux listes<\/li><li>1.4 Questions de curiosit\u00e9<\/li><li>1.5 Organigramme du type et de la firme<\/li><\/ul><p>Chapitre 2 &#8211; Pourquoi font-ils cela ?<\/p><ul><li>2.1 &#8211; Tableau des objectifs erron\u00e9s<\/li><li>2.2 &#8211; Des erreurs, vraiment ?<\/li><li>2.3 &#8211; Penser, ressentir et d\u00e9cider<\/li><li>2.4 &#8211; Carte sup\u00e9rieure<\/li><\/ul><p>Chapitre 3 &#8211; Se mettre sur la m\u00eame longueur d&rsquo;onde<\/p><ul><li>3.1 &#8211; Planification de la transition<\/li><li>3.2 &#8211; Savent-ils que vous vous souciez d&rsquo;eux ?<\/li><li>3.3 &#8211; En cas de d\u00e9saccord entre les enseignants<\/li><\/ul><p>Chapitre 4 &#8211; Outils de coop\u00e9ration et de suivi<\/p><ul><li>4.1 &#8211; Encouragement vs. louange<\/li><li>4.2 &#8211; Le pouvoir du silence : Le maintien des limites<\/li><li>4.3 &#8211; R\u00e9ponses respectueuses aux comportements irrespectueux<\/li><li>4.4 &#8211; J&rsquo;ai besoin d&rsquo;un c\u00e2lin ou d&rsquo;un coup de main<\/li><li>4.5 &#8211; Outils ou astuces<\/li><\/ul><p>Chapitre 5 &#8211; Attention aux cons\u00e9quences logiques<\/p><ul><li>5.1 &#8211; Cons\u00e9quences logiques<\/li><li>5.2 &#8211; R\u00e9solution de probl\u00e8mes<\/li><li>5.3 &#8211; D\u00e9cider de ce que vous allez faire<\/li><li>5.4 &#8211; Choix limit\u00e9s<\/li><li>5.5 &#8211; Cons\u00e9quences naturelles<\/li><\/ul><p>Chapitre 6 &#8211; L&rsquo;autor\u00e9gulation et le cerveau<\/p><ul><li>6.1 &#8211; Le cerveau dans la paume de votre main<\/li><li>6.2 &#8211; Temporisation positive<\/li><li>6.3 &#8211; La roue du choix<\/li><\/ul><p>Chapitre 7 &#8211; Communiquer pour coop\u00e9rer et comprendre<\/p><ul><li>7.1 &#8211; G\u00e9ant comp\u00e9tent<\/li><li>7.2 &#8211; Les 3 R de la r\u00e9cup\u00e9ration<\/li><li>7.3 &#8211; Questions de curiosit\u00e9 &#8211; Conversationnel<\/li><li>7.4 &#8211; \u00c9coute r\u00e9flexive<\/li><\/ul><p>Chapitre 8 &#8211; Faire la paix<\/p><ul><li>8.1 &#8211; Messages \u00ab\u00a0I<\/li><li>8.2 &#8211; Pourquoi la r\u00e9solution des conflits \u00e9choue et que faire ?<\/li><li>8.3 &#8211; Processus de r\u00e9solution des conflits<\/li><\/ul><p>Chapitre 9 &#8211; Tout mettre en place &#8211; La r\u00e9union de classe<\/p><ul><li>9.1 &#8211; Introduction aux r\u00e9unions de classe<\/li><li>9.2 &#8211; R\u00e9union de classe 6+<\/li><li>9.3 &#8211; R\u00e9union de classe 3-6<\/li><\/ul><p>Chapitre 10 &#8211; Le continuum du changement<\/p><ul><li>10.1 &#8211; Appartenance et signification<\/li><li>10.2 &#8211; Le cerveau dans le c\u0153ur<\/li><li>10.3 &#8211; Conclusion<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec668ed elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec668ed\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-58d2f99\" data-id=\"58d2f99\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fb02e69 elementor-widget elementor-widget-image\" data-id=\"fb02e69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"432\" src=\"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2022\/11\/PDMCLPInstructors-768x432.jpg\" class=\"attachment-medium_large size-medium_large wp-image-8668\" alt=\"\" srcset=\"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2022\/11\/PDMCLPInstructors-768x432.jpg 768w, https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2022\/11\/PDMCLPInstructors-300x169.jpg 300w, https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2022\/11\/PDMCLPInstructors-1024x576.jpg 1024w, https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2022\/11\/PDMCLPInstructors-1536x864.jpg 1536w, https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2022\/11\/PDMCLPInstructors-600x338.jpg 600w, https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2022\/11\/PDMCLPInstructors.jpg 1920w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le cours virtuel Discipline positive dans la classe Montessori est une adaptation pratique et approfondie de l&rsquo;approche de la Discipline positive en mati\u00e8re de gestion du comportement, qui est \u00e9troitement li\u00e9e aux principes et pratiques Montessori. Il fournit un ensemble d&rsquo;outils inestimables qui d\u00e9veloppent les comp\u00e9tences introduites dans les programmes de formation des enseignants Montessori et constitue une remise \u00e0 niveau parfaite pour les guides Montessori exp\u00e9riment\u00e9s qui souhaitent am\u00e9liorer la culture de leur classe, renforcer leurs relations avec les enfants et les familles et cr\u00e9er des communaut\u00e9s d&rsquo;apprentissage toujours plus pacifiques et harmonieuses. <\/p>\n<p><strong>Remise de groupe &#8211; Appliqu\u00e9e \u00e0 la caisse<\/strong><\/p>\n<ul>\n<li>3-5 participants &#8211; 10%<\/li>\n<li>6-10 participants &#8211; 15%<\/li>\n<li>11-20 participants &#8211; 20<\/li>\n<li>21-30 participants &#8211; 25%<\/li>\n<li>31-50 participants &#8211; 30<\/li>\n<li>50 ou plus &#8211; 50<\/li>\n<\/ul>\n<p><strong>Les groupes peuvent ajouter des sessions Zoom en direct pour les questions-r\u00e9ponses. P <\/strong><span style=\"box-sizing: border-box;\"><strong>bail <\/strong><a href=\"https:\/\/pdmc-montessori.org\/fr\/contactez-nous\/\" target=\"_blank\" rel=\"noopener\"><strong>contactez-nous<\/strong><\/a><\/span><strong> pour obtenir des informations sur les prix et les horaires.<\/strong><\/p>\n","protected":false},"featured_media":9161,"template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"disabled","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}}},"product_brand":[],"product_cat":[424],"product_tag":[],"class_list":{"0":"post-11772","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-formation-en-ligne","7":"desktop-align-left","8":"tablet-align-left","9":"mobile-align-left","11":"first","12":"instock","13":"downloadable","14":"virtual","15":"taxable","16":"purchasable","17":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cours vid\u00e9o sur la discipline positive dans la classe Montessori - Positive Discipline in the Montessori Classroom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cours vid\u00e9o sur la discipline positive dans la classe Montessori - Positive Discipline in the Montessori Classroom\" \/>\n<meta property=\"og:description\" content=\"Le cours virtuel Discipline positive dans la classe Montessori est une adaptation pratique et approfondie de l&#039;approche de la Discipline positive en mati\u00e8re de gestion du comportement, qui est \u00e9troitement li\u00e9e aux principes et pratiques Montessori. Il fournit un ensemble d&#039;outils inestimables qui d\u00e9veloppent les comp\u00e9tences introduites dans les programmes de formation des enseignants Montessori et constitue une remise \u00e0 niveau parfaite pour les guides Montessori exp\u00e9riment\u00e9s qui souhaitent am\u00e9liorer la culture de leur classe, renforcer leurs relations avec les enfants et les familles et cr\u00e9er des communaut\u00e9s d&#039;apprentissage toujours plus pacifiques et harmonieuses.  Remise de groupe - Appliqu\u00e9e \u00e0 la caisse  3-5 participants - 10%  6-10 participants - 15%  11-20 participants - 20  21-30 participants - 25%  31-50 participants - 30  50 ou plus - 50 Les groupes peuvent ajouter des sessions Zoom en direct pour les questions-r\u00e9ponses. P bail contactez-nous pour obtenir des informations sur les prix et les horaires.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/\" \/>\n<meta property=\"og:site_name\" content=\"Positive Discipline in the Montessori Classroom\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-11T01:55:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2023\/10\/PDMCProduct1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"717\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/product\\\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\\\/\",\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/product\\\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\\\/\",\"name\":\"Cours vid\u00e9o sur la discipline positive dans la classe Montessori - Positive Discipline in the Montessori Classroom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/product\\\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/product\\\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PDMCProduct1.jpg\",\"datePublished\":\"2023-10-30T15:36:31+00:00\",\"dateModified\":\"2025-06-11T01:55:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/product\\\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/product\\\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/product\\\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PDMCProduct1.jpg\",\"contentUrl\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/PDMCProduct1.jpg\",\"width\":717,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/product\\\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/page-daccueil-du-cd\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"https:\\\/\\\/pdmc-montessori.org\\\/boutique\\\/?lang=fr\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cours vid\u00e9o sur la discipline positive dans la classe Montessori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/\",\"name\":\"Positive Discipline in the Montessori Classroom\",\"description\":\"Positive Discipline training for Montessori educators\",\"publisher\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b4869f122ec229aca6c597b8b59f661\"},\"alternateName\":\"PDMC Montessori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/fr\\\/#\\\/schema\\\/person\\\/6b4869f122ec229aca6c597b8b59f661\",\"name\":\"Chip DeLorenzo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-PDMC-Website-Logo-1-1.png\",\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-PDMC-Website-Logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-PDMC-Website-Logo-1-1.png\",\"width\":1554,\"height\":395,\"caption\":\"Chip DeLorenzo\"},\"logo\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-PDMC-Website-Logo-1-1.png\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cours vid\u00e9o sur la discipline positive dans la classe Montessori - Positive Discipline in the Montessori Classroom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/","og_locale":"fr_FR","og_type":"article","og_title":"Cours vid\u00e9o sur la discipline positive dans la classe Montessori - Positive Discipline in the Montessori Classroom","og_description":"Le cours virtuel Discipline positive dans la classe Montessori est une adaptation pratique et approfondie de l'approche de la Discipline positive en mati\u00e8re de gestion du comportement, qui est \u00e9troitement li\u00e9e aux principes et pratiques Montessori. Il fournit un ensemble d'outils inestimables qui d\u00e9veloppent les comp\u00e9tences introduites dans les programmes de formation des enseignants Montessori et constitue une remise \u00e0 niveau parfaite pour les guides Montessori exp\u00e9riment\u00e9s qui souhaitent am\u00e9liorer la culture de leur classe, renforcer leurs relations avec les enfants et les familles et cr\u00e9er des communaut\u00e9s d'apprentissage toujours plus pacifiques et harmonieuses.  Remise de groupe - Appliqu\u00e9e \u00e0 la caisse  3-5 participants - 10%  6-10 participants - 15%  11-20 participants - 20  21-30 participants - 25%  31-50 participants - 30  50 ou plus - 50 Les groupes peuvent ajouter des sessions Zoom en direct pour les questions-r\u00e9ponses. P bail contactez-nous pour obtenir des informations sur les prix et les horaires.","og_url":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/","og_site_name":"Positive Discipline in the Montessori Classroom","article_modified_time":"2025-06-11T01:55:03+00:00","og_image":[{"width":717,"height":800,"url":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2023\/10\/PDMCProduct1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/","url":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/","name":"Cours vid\u00e9o sur la discipline positive dans la classe Montessori - Positive Discipline in the Montessori Classroom","isPartOf":{"@id":"https:\/\/pdmc-montessori.org\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/#primaryimage"},"image":{"@id":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/#primaryimage"},"thumbnailUrl":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2023\/10\/PDMCProduct1.jpg","datePublished":"2023-10-30T15:36:31+00:00","dateModified":"2025-06-11T01:55:03+00:00","breadcrumb":{"@id":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/#primaryimage","url":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2023\/10\/PDMCProduct1.jpg","contentUrl":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2023\/10\/PDMCProduct1.jpg","width":717,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/pdmc-montessori.org\/fr\/product\/cours-video-sur-la-discipline-positive-dans-la-classe-montessori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pdmc-montessori.org\/fr\/page-daccueil-du-cd\/"},{"@type":"ListItem","position":2,"name":"Boutique","item":"https:\/\/pdmc-montessori.org\/boutique\/?lang=fr"},{"@type":"ListItem","position":3,"name":"Cours vid\u00e9o sur la discipline positive dans la classe Montessori"}]},{"@type":"WebSite","@id":"https:\/\/pdmc-montessori.org\/fr\/#website","url":"https:\/\/pdmc-montessori.org\/fr\/","name":"Positive Discipline in the Montessori Classroom","description":"Positive Discipline training for Montessori educators","publisher":{"@id":"https:\/\/pdmc-montessori.org\/fr\/#\/schema\/person\/6b4869f122ec229aca6c597b8b59f661"},"alternateName":"PDMC Montessori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pdmc-montessori.org\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":["Person","Organization"],"@id":"https:\/\/pdmc-montessori.org\/fr\/#\/schema\/person\/6b4869f122ec229aca6c597b8b59f661","name":"Chip DeLorenzo","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2025\/03\/cropped-PDMC-Website-Logo-1-1.png","url":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2025\/03\/cropped-PDMC-Website-Logo-1-1.png","contentUrl":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2025\/03\/cropped-PDMC-Website-Logo-1-1.png","width":1554,"height":395,"caption":"Chip DeLorenzo"},"logo":{"@id":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2025\/03\/cropped-PDMC-Website-Logo-1-1.png"}}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/product\/11772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/product\/11772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/media\/9161"}],"wp:attachment":[{"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/media?parent=11772"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/product_brand?post=11772"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/product_cat?post=11772"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/pdmc-montessori.org\/fr\/wp-json\/wp\/v2\/product_tag?post=11772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}