{"id":10691,"date":"2020-11-18T19:50:20","date_gmt":"2020-11-19T00:50:20","guid":{"rendered":"https:\/\/pdmc-montessori.org\/pratiche-in-classe-che-creano-connessione\/"},"modified":"2025-06-10T18:50:28","modified_gmt":"2025-06-10T22:50:28","slug":"pratiche-in-classe-che-creano-connessione","status":"publish","type":"post","link":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/","title":{"rendered":"Pratiche in classe che creano connessione"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"10691\" class=\"elementor elementor-10691 elementor-109\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7dadee7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7dadee7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-11a78e5\" data-id=\"11a78e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5873610 elementor-widget elementor-widget-text-editor\" data-id=\"5873610\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>1. Coinvolgere i bambini nella creazione di regole di base e routine<\/strong><\/p><p>Le routine danno ai bambini l&#8217;opportunit\u00e0 di prevedere cosa accadr\u00e0 dopo. Quando i bambini sono in grado di prevedere cosa accadr\u00e0 dopo, hanno la possibilit\u00e0 di prendere decisioni su come prepararsi al meglio per ci\u00f2 che accadr\u00e0 dopo (transizioni, cose che piacciono o non piacciono, ecc.). Sono in grado di autoregolarsi.  <\/p><p>Le regole di base permettono ai bambini di sapere quali sono le aspettative. Sono confini, o limiti, con cui i bambini si muovono all&#8217;interno della comunit\u00e0 scolastica e mantengono il rispetto e la collaborazione reciproca. In una classe Montessori le regole di base sono semplici e poche e insegniamo le abilit\u00e0 necessarie per seguirle.  <\/p><p>Coinvolgere i bambini nella creazione di regole di base e routine invita alla cooperazione, al rispetto e al legame. Inoltre, quando i bambini aiutano a creare le regole di base, con la guida dell&#8217;insegnante, sono anche pi\u00f9 disposti ad aiutare a mantenere le regole di base in classe. Se le regole di base sono state applicate e seguite con costanza, i bambini pi\u00f9 grandi prenderanno a modello gli adulti e aiuteranno i bambini pi\u00f9 piccoli. Quando i bambini si aiutano a vicenda, sperimentano la responsabilit\u00e0 sociale e quindi un senso di appartenenza e di comunit\u00e0.   <\/p><p>Nell&#8217;appendice troverai delle attivit\u00e0 che ti aiuteranno a coinvolgere i bambini nella creazione delle routine e delle linee guida della classe.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9fab98b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9fab98b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f287ba8\" data-id=\"f287ba8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ae9f9c4 elementor-widget elementor-widget-text-editor\" data-id=\"ae9f9c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>2. Le tradizioni<\/strong><\/p><p>Come le tradizioni familiari, le tradizioni in classe danno ai bambini un senso di identit\u00e0 come membri della comunit\u00e0 scolastica. Le tradizioni segnano il tempo, la crescita e la maturit\u00e0. Le tradizioni celebrano la nostra appartenenza alla comunit\u00e0 scolastica. Le passeggiate di compleanno, le celebrazioni delle festivit\u00e0, le lezioni e le attivit\u00e0 annuali sono segnali per i bambini e li aiutano a vedersi come parte di qualcosa di pi\u00f9 grande di loro. Le tradizioni, inoltre, danno alla comunit\u00e0 l&#8217;opportunit\u00e0 di risolvere i problemi e di pianificare e di vedere il piano realizzarsi. Poich\u00e9 nella maggior parte dei casi abbiamo i bambini per tre anni interi, noi montessoriani abbiamo la straordinaria opportunit\u00e0 di sviluppare tradizioni in classe che saranno ricordate dai nostri bambini e dagli adulti per gli anni a venire: ricordi del tempo che abbiamo condiviso insieme e del legame che avremo sempre.     <\/p><p>Ora che non sono pi\u00f9 in classe a tempo pieno, \u00e8 pi\u00f9 difficile conoscere tutti i bambini della scuola, come facevo quando avevo la mia classe. Mi mancano quel legame, i legami che si creavano come comunit\u00e0 e soprattutto le tradizioni che ci legavano. Tuttavia, una delle tradizioni emerse nella nostra scuola \u00e8 un gioco chiamato &#8220;Monster Ball&#8221;, nato molti anni fa quando ero l &#8220;insegnante della Casa dei Bambini. \u00c8 iniziato quando giocavo con i bambini. A loro piaceva molto quando ero io \u2018il mostro\u2019 e hanno iniziato a chiamarmi \u2018il mostro\u2019 mentre li inseguivo. Con il passare del tempo il gioco si \u00e8 evoluto in un semplice \u2018Mostro\u2019, in cui io fingevo di essere un mostro e li inseguivo (a questo punto era uno di quei giochi che loro amavano molto pi\u00f9 di me e io ero sempre un po&#8221; preoccupata di quello che avrebbero potuto pensare i genitori quando avrebbero saputo che inseguivo i loro figli nel parco giochi fingendo di essere un mostro). Quando i bambini sono entrati nel programma elementare della nostra scuola, il gioco si \u00e8 evoluto nuovamente in una versione di dodge ball del &#8220;Monster Tag&#8221;, in cui lanciavo palle Nerf dodge ai bambini nel tentativo di farli scappare. Alla fine si chiam\u00f2 &#8220;Monster Ball&#8221;. Cerco ancora di uscire una volta a settimana per giocare a &#8220;Monster Ball&#8221; con gli studenti delle elementari. I nostri studenti delle medie di solito non giocano, ma alla fine dell &#8220;anno, quando gli studenti dell&#8221; ottavo anno iniziano ad accettare il fatto che non saranno pi\u00f9 nella nostra scuola, \u00e8 sorprendente vederli riunirsi a noi per le loro ultime partite di &#8220;Monster Ball&#8221;. (Nota: in 15 anni, al momento della stesura di questo libro, ho ricevuto solo una piccola lamentela su &#8220;Monster Ball&#8221;, e ora vendiamo le feste di &#8220;Monster Ball&#8221; alla nostra asta annuale, e sono sempre molto vendute).          <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0ee5e1c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0ee5e1c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ddc3f72\" data-id=\"ddc3f72\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f6b1b5 elementor-widget elementor-widget-text-editor\" data-id=\"2f6b1b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>3. Senso dell&#8217;umorismo<\/strong><\/p><p>Tutti hanno il senso dell&#8217;umorismo! Quando gli adulti condividono il loro senso dell&#8217;umorismo con i bambini, ridono di loro stessi e delle battute dei bambini o condividono le loro stesse battute, si rendono vulnerabili. Mostrano ai bambini che sono umani. Quando sappiamo che gli altri sono umani, ci permettono di essere liberi di esserlo. L&#8217;umorismo alleggerisce lo stress delle situazioni difficili e ci aiuta a ricordare ci\u00f2 che \u00e8 davvero importante.    <\/p><p>Esito a scrivere questa storia, ma correr\u00f2 il rischio di condividere con te la mia umanit\u00e0. Sono una di quelle strane persone che amano lavorare con gli studenti delle scuole medie. Quando ho iniziato a lavorare con gli studenti delle scuole medie ho iniziato in modo piuttosto serio. Volevo assicurarmi che i limiti fossero rispettati, che gli studenti mi prendessero sul serio e che mi rispettassero (caratteristiche non indifferenti per un insegnante di scuola media). Col senno di poi, e con qualche anno di esperienza alle spalle, ora so di essere stata un po&#8217; rigida. Tutto questo \u00e8 finito un giorno durante una riunione di classe. Uno dei miei strumenti per ottenere la collaborazione degli studenti in cerchio era (ed \u00e8) quello di sedermi in silenzio finch\u00e9 gli studenti non si calmano. A volte rimango seduto anche un minuto o due in pi\u00f9 del necessario per chiarire un punto. Questo \u00e8 ci\u00f2 che stavo facendo. Mentre io e gli studenti eravamo seduti in completo silenzio, uno dei ragazzi pi\u00f9 tranquilli della classe ha sentito il vento molto forte. All&#8217;inizio ho semplicemente cercato di ignorarlo e di rimanere in silenzio (e serio). Ma il momento sembrava davvero uscito da una sceneggiatura cinematografica. Il momento non poteva essere peggiore per cercare di rimanere serio. I bambini mi guardavano tutti aspettando di vedere la mia risposta. Ho iniziato a ridere internamente e poi ho iniziato a diventare viola mentre cercavo di resistere. Prima di rendermene conto, ero crollata sul pavimento e stavo ridendo cos\u00ec tanto da piangere. Non sono riuscita a smettere di ridere per quasi due minuti. Naturalmente, non appena ho iniziato a ridere, tutti gli studenti sono scoppiati a ridere, compreso il ragazzo che aveva perso il fiato. \u00c8 stato in quel momento che la nostra classe \u00e8 diventata davvero umana (o forse sono stato io a diventare umano). L&#8217;intero tono della classe \u00e8 cambiato e abbiamo iniziato a conoscerci meglio. Se lavori con gli studenti delle scuole medie, sai quanto sia importante questo momento!                    <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ef91512 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ef91512\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bfef9ba\" data-id=\"bfef9ba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bc5cddd elementor-widget elementor-widget-text-editor\" data-id=\"bc5cddd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>4. Prendersi del tempo per divertirsi insieme<\/strong><\/p><p>C&#8217;\u00e8 cos\u00ec tanto da fare e cos\u00ec poco tempo. I tre anni in cui i bambini sono nella nostra classe passano cos\u00ec in fretta. Non dimentichiamoci di goderceli. Prendersi del tempo per divertirsi insieme \u00e8 una parte importante del rapporto con i bambini. Alcuni dei miei ricordi preferiti della classe sono le volte in cui facevamo una ricreazione al chiuso a causa della pioggia o del fango (che qui nel Maine \u00e8 molto frequente in primavera). Prendevamo i giochi da tavolo e giocavamo insieme. Quei momenti sono cos\u00ec importanti. Mi ricordavano chi erano i bambini al di fuori del mio programma quotidiano di impartire lezioni e dirigere attivit\u00e0 mirate. Questa attivit\u00e0 apparentemente improduttiva ha favorito la connessione tra tutti noi. Per me, ha permesso ai bambini di diventare soggetti e non oggetti. Ho scoperto chi erano, quanto erano divertenti e quanto mi piacevano come persone. Ho avuto modo di conoscerli molto meglio e loro hanno avuto la possibilit\u00e0 di conoscere meglio me. \u00c8 stato un modo cos\u00ec potente di entrare in contatto, che \u00e8 valso ogni momento che ho investito.            <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d20aff5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d20aff5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-480ea2d\" data-id=\"480ea2d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b6f722 elementor-widget elementor-widget-text-editor\" data-id=\"6b6f722\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>5. Dedicare del tempo speciale<\/strong><\/p><p>Dedicare del tempo, individualmente, ai bambini fa parte di ci\u00f2 che facciamo come Montessoriani. Dedichiamo gran parte della nostra giornata, durante il ciclo di lavoro di 3 ore, a lezioni individuali e di piccolo gruppo. Questo \u00e8 ci\u00f2 che facciamo come parte della nostra routine quotidiana per collegare i bambini al lavoro in classe. Il tempo speciale non \u00e8 semplicemente un \u201cattenzione individuale, come aiutare un bambino a svolgere il suo lavoro, anche se potrebbe far parte del piano. Il tempo speciale \u00e8 un tempo riservato con l\u201d unico scopo di favorire la connessione e lo sviluppo di un rapporto pi\u00f9 profondo con i bambini nelle nostre classi. Non \u00e8 necessario che questo tempo sia lungo, n\u00e9 che esuli dalla nostra normale routine. Ecco alcuni esempi:      <\/p><ul><li>Pranzare con uno studente al giorno in un tavolo da due persone.<\/li><li>Prendersi un momento per chiedere a un bambino quali sono i suoi interessi o le sue attivit\u00e0 al di fuori della scuola.<\/li><li>Invitare un bambino ad aiutarti in un compito in classe.<\/li><li>Creare una routine che permetta al bambino di contare sulla tua presenza. Questo funziona particolarmente bene con i bambini il cui obiettivo errato \u00e8 l&#8217;attenzione, e d\u00e0 al bambino l&#8217;autonomia di poter gestire le proprie emozioni e i propri desideri mentre anticipa questo momento. La routine potrebbe consistere semplicemente nel leggere insieme prima dell&#8217;inizio della giornata.  <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-da9921d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"da9921d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4ee4ba9\" data-id=\"4ee4ba9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-106c31b elementor-widget elementor-widget-text-editor\" data-id=\"106c31b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>6. Apprezzare l&#8217;unicit\u00e0<\/strong><\/p><p>Hai mai notato che i nostri maggiori punti di forza sembrano essere anche le nostre maggiori debolezze? Anche i bambini sembrano essere costruiti in questo modo. \u00c8 interessante la rapidit\u00e0 con cui giudichiamo i tratti caratteriali degli altri, per poi scoprire che \u00e8 solo la nostra percezione o la nostra sensibilit\u00e0 a scatenare una reazione negativa. Invece di giudicare le caratteristiche, cosa succederebbe se le riconoscessimo semplicemente come caratteristiche uniche? \u00c8 possibile che in questo modo riusciamo a vedere anche gli elementi positivi di queste caratteristiche, invece che solo quelli negativi.    <\/p><p>Il bambino disordinato \u00e8 anche creativo? Il bambino dispotico \u00e8 un lavoratore organizzato? Quel bambino aggressivo difende i suoi amici? Il bambino maldestro \u00e8 compassionevole e disponibile?   <\/p><p>Dedicare del tempo a riconoscere e incoraggiare queste unicit\u00e0 d\u00e0 ai bambini la sicurezza di sapere che li vedi davvero per quello che sono. E quando qualcuno vede davvero chi siamo, non si crea forse un legame tra te e lui e non ti aiuta a vedere te stesso in modo pi\u00f9 chiaro e compassionevole? <\/p><p><em>&#8220;Samantha, apprezzo molto l&#8217;accuratezza con cui svolgi il tuo lavoro. Quando ti interessa qualcosa, scendi davvero in profondit\u00e0&#8221;.<\/em><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-77ac629 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"77ac629\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a5debe\" data-id=\"8a5debe\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4da444 elementor-widget elementor-widget-text-editor\" data-id=\"e4da444\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>7. Esprimere fiducia dando ai bambini l&#8217;opportunit\u00e0 di contribuire in modo significativo (punti di forza)<\/strong><\/p><p>Le persone prosperano quando si fidano di loro e vanno oltre per aiutare quando si sentono in grado di farlo. I bambini sono molto capaci. Questo \u00e8 il punto di partenza della filosofia Montessori. Partiamo dalla comprensione e dalla convinzione che i bambini siano capaci, che vogliano imparare, che vogliano contribuire, che vogliano cooperare e diventare membri della comunit\u00e0. Iniziare in un altro modo tradisce tutto ci\u00f2 in cui crediamo. Crediamo nel potenziale umano e nella nostra capacit\u00e0 di creare un ambiente che lo liberi. Abbiamo fiducia nei bambini.      <\/p><p>\u201cNon fare mai per un bambino quello che pu\u00f2 fare per se stesso\u201d. (Montessori). Anche questo \u00e8 un punto di partenza. Ma non finisce qui. I bambini si sentono in sintonia e a posto quando sanno di poter contribuire in modo significativo alla loro comunit\u00e0. Il nostro obbligo nei confronti dei bambini non \u00e8 solo quello di aiutarli a diventare indipendenti, ma dobbiamo anche fornire loro gli strumenti per diventare membri attivi della loro comunit\u00e0. Offrire opportunit\u00e0 di contributo significativo \u00e8 uno dei modi pi\u00f9 efficaci per raggiungere questo obiettivo vitale.     <\/p><p>Come discuteremo pi\u00f9 dettagliatamente nel prossimo capitolo, la creazione di lavori in classe \u00e8 un modo per incoraggiare un contributo significativo da parte dei bambini. Ecco altre riflessioni: <\/p><ul><li>Scopri quali sono i talenti dei bambini e mettili a frutto!<\/li><li>Cerca ogni occasione per delegare i compiti ai bambini in classe (fare le fotocopie, fare le pulizie, plastificare, aiutare a prepararsi per gli eventi, aiutare a preparare il materiale per la classe, guidare un cerchio). Esamina i compiti che svolgi quotidianamente e considera quali potrebbero essere svolti dai bambini. Ricorda che non lo fanno per te, ma per dare un contributo significativo alla comunit\u00e0.  <\/li><li>Non aspettare che i bambini si aiutino a vicenda con il lavoro in classe, ma incoraggiali a cercare bambini specifici che possano aiutarli. Ad esempio, se un bambino ha appena iniziato il gioco dei francobolli e ha bisogno di aiuto, chiedi a un bambino che ha appena imparato quel materiale di aiutarlo, oppure chiedi al bambino che ha bisogno di aiuto di chiedere al bambino che ha imparato quel materiale. <\/li><li>Assicurati che i lavori in classe (lavoretti) siano davvero significativi, non solo dei segnaposto. Ad esempio, se nella tua classe ci sono 25 bambini e solo 20 faccende domestiche che devono essere svolte davvero, evita di creare dei lavori sostitutivi in modo che tutti abbiano un compito da svolgere. I bambini sanno quando il lavoro non \u00e8 un vero lavoro e si comporteranno di conseguenza.  <\/li><li>Fai attenzione a dare un lavoro significativo solo ai bambini che si sono \u201cguadagnati\u201d la tua fiducia. Considera che tutti i bambini trovano appartenenza e significato attraverso contributi significativi e che i comportamenti scorretti spesso iniziano a scomparire quando i bambini sperimentano una vera responsabilit\u00e0 sociale. <\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dae03ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dae03ea\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7ab188f\" data-id=\"7ab188f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47a7475 elementor-widget elementor-widget-text-editor\" data-id=\"47a7475\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>8. Concentrarsi sul progresso, non sulla perfezione<\/strong><\/p><p>Tutti abbiamo i nostri ideali e la maggior parte di noi non \u00e8 soddisfatta se non raggiunge i propri obiettivi. Molti di noi hanno imparato in famiglie o classi pi\u00f9 autoritarie che gli obiettivi sono \u201cpass\/fail\u201d. O li hai raggiunti o non li hai raggiunti. Ci concentriamo sempre su ci\u00f2 che possiamo fare meglio, sulle nostre aree di debolezza e su ci\u00f2 che dobbiamo fare per correggerle.   <\/p><p>Un anno, in una delle mie classi elementari, stavamo facendo una riunione di classe. La riunione di classe riguardava un bambino, James, che aveva fatto del male agli altri bambini, intenzionalmente. I bambini erano frustrati e pi\u00f9 di un genitore mi aveva parlato dell&#8217;aggressivit\u00e0 di James nei confronti degli altri studenti. Era primavera e l&#8217;argomento era stato affrontato pi\u00f9 volte nel corso dell&#8217;anno. I bambini insistevano sul fatto che l&#8217;argomento era stato affrontato pi\u00f9 volte nel corso dell&#8217;anno e che continuava a verificarsi. Un bambino ha commentato, con esasperazione, che doveva perdere tempo a parlarne ancora, visto che sarebbe successo di nuovo.     <\/p><p>Obiettivamente, l \u201caggressione era ancora in corso. Ma James aveva fatto passi da gigante durante l\u201d anno, in gran parte grazie al lavoro svolto durante le riunioni di classe. Ormai era raro che James facesse del male a un compagno di classe, forse una volta ogni due settimane. All \u201cinizio dell\u201d anno succedeva un paio di volte a settimana. Durante la discussione nella nostra riunione di classe, ho fatto una semplice domanda, quando i bambini hanno espresso la loro frustrazione nel doverne parlare di nuovo. Ho chiesto: \u201cJames \u00e8 migliorato da quando abbiamo iniziato a parlarne in classe?\u201d. E cos\u00ec \u00e8 stato. Da quel momento il tono della discussione \u00e8 cambiato. I bambini hanno riconosciuto che aveva fatto molti progressi e si sono resi conto che i loro sforzi avevano avuto un impatto significativo. Iniziarono anche a riconoscerlo durante la parte della riunione di classe in cui i bambini si fanno i complimenti e gli apprezzamenti reciproci. Poco dopo quell \u201cincontro, l\u201d aggressivit\u00e0 di James scomparve del tutto. Rimase nella nostra classe per altri tre anni e non colp\u00ec mai pi\u00f9 un altro bambino. Una storia vera.            <\/p><p>Togliamo l \u201cattenzione dalle nostre lacune e concentriamoci sui nostri progressi. La perfezione non \u00e8 raggiungibile, ma se cerchiamo ogni giorno di fare un po\u201d meglio, possiamo tutti fare dei progressi. E quando riconosciamo questi progressi, piuttosto che la strada che dobbiamo ancora percorrere, siamo incoraggiati a continuare a impegnarci e quindi a fare ulteriori progressi.  <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4dd01a7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4dd01a7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6e94305\" data-id=\"6e94305\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cfe65a elementor-widget elementor-widget-text-editor\" data-id=\"3cfe65a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>9. Collaborare con i bambini per risolvere i problemi insieme<\/strong><\/p><p>Coinvolgere i bambini nel processo di risoluzione dei problemi invita alla responsabilit\u00e0 e alla cooperazione nell&#8217;ambiente scolastico. Inoltre, aiuta gli adulti della classe a scoprire quanto i bambini siano capaci e quanto vogliano davvero creare un ambiente cooperativo e rispettoso (nonostante quello che sembra a volte). <\/p><p>Risolvere i problemi come comunit\u00e0 utilizzando le Riunioni di Classe crea una struttura in cui i bambini si riuniscono per aiutarsi a risolvere i problemi. I bambini presentano i loro problemi all&#8217;ordine del giorno della riunione di classe, ne discutono apertamente, senza colpevolizzarsi, e lavorano per risolverli insieme. Attraverso questo processo i bambini hanno la possibilit\u00e0 di sviluppare empatia, capacit\u00e0 di risolvere i problemi, capacit\u00e0 di comunicazione e responsabilit\u00e0 sociale. La classe stessa ha la possibilit\u00e0 di sviluppare un profondo senso di comunit\u00e0, in quanto i singoli bambini e il gruppo condividono apertamente i loro problemi e si interessano non solo alle loro difficolt\u00e0, ma anche a quelle dei loro compagni. Il legame che si forma da questo processo \u00e8 qualcosa che nessun insegnante dovrebbe mai perdere.    <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c111b50 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c111b50\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-306b2d6\" data-id=\"306b2d6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0782aa5 elementor-widget elementor-widget-text-editor\" data-id=\"0782aa5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>10. Essere vulnerabili<\/strong><\/p><p>Non so tu, ma io ho fatto molti errori come insegnante. E continuo a commettere errori. Non molto tempo fa, stavo insegnando una lezione di algebra ad alcuni studenti della scuola media. Non ho guardato avanti e non mi sono preparata per la lezione. Insegno Algebra da 18 anni e ho dato per scontato di poter tenere la lezione al volo. Ho fatto un pessimo lavoro e ho dovuto rivedere la lezione mentre la svolgevo. Dopo circa 15 minuti di inciampo, mi sono fermata e ho detto agli studenti: &#8220;Vi chiedo di fare i compiti ogni sera e di venire in classe preparati&#8221;. Ho dato per scontato di poter insegnare questa lezione senza ripassarla e non ho fatto i compiti. Vi chiedo di risolvere i vostri problemi quando commettete degli errori e ora devo risolvere i miei. Perch\u00e9 non ti prendi il resto della lezione per recuperare i compiti mancati? Non ci sono compiti per stasera. Far\u00f2 questa lezione domani&#8221;.      <\/p><p>Non avrei mai ammesso una cosa del genere durante i miei primi anni di insegnamento. Mi portavo ancora dietro l \u201cinconscia illusione di non dover ammettere i miei errori di fronte ai bambini, perch\u00e9 avrebbero capito che sono debole e fallibile. Pi\u00f9 a lungo ho insegnato, per\u00f2, \u00e8 diventato chiaro che i miei tentativi di nascondere le mie imperfezioni ai bambini erano vani. Sembrava che lo sapessero comunque. E quando cercavo di nasconderle, in realt\u00e0 si creava una frattura tra me e i bambini, perch\u00e9 sapevano (come gli adulti) che avevo commesso molti errori. Quando ho iniziato a confessare, \u00e8 successo qualcosa di incredibile. Anche loro hanno iniziato ad assumersi le proprie responsabilit\u00e0. La fiducia \u00e8 cresciuta, la necessit\u00e0 di rimproverarsi a vicenda gli errori \u00e8 scomparsa e i bambini hanno imparato a perdonarsi pi\u00f9 facilmente. Pensa all\u201d ultima volta che qualcuno ha ammesso onestamente il proprio errore e si \u00e8 assunto la responsabilit\u00e0 delle proprie azioni. Qual \u00e8 stata la tua reazione? Hai sentito il bisogno di punirlo per le sue azioni o ti sei sentito chiamato alla misericordia e al perdono? Tutto parte da noi. I nostri modelli e le nostre azioni si ripercuotono nella classe.            <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1. Coinvolgere i bambini nella creazione di regole di base e routine Le routine danno ai bambini l&#8217;opportunit\u00e0 di prevedere cosa accadr\u00e0 dopo. Quando i bambini sono in grado di prevedere cosa accadr\u00e0 dopo, hanno [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":5969,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[230],"tags":[],"class_list":["post-10691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pratiche in classe che creano connessione - Positive Discipline in the Montessori Classroom<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pratiche in classe che creano connessione - Positive Discipline in the Montessori Classroom\" \/>\n<meta property=\"og:description\" content=\"1. Coinvolgere i bambini nella creazione di regole di base e routine Le routine danno ai bambini l&#8217;opportunit\u00e0 di prevedere cosa accadr\u00e0 dopo. Quando i bambini sono in grado di prevedere cosa accadr\u00e0 dopo, hanno [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/\" \/>\n<meta property=\"og:site_name\" content=\"Positive Discipline in the Montessori Classroom\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-19T00:50:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-10T22:50:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2020\/11\/Classpracticesrsv2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1172\" \/>\n\t<meta property=\"og:image:height\" content=\"581\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Chip DeLorenzo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Chip DeLorenzo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"15 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/\"},\"author\":{\"name\":\"Chip DeLorenzo\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/#\\\/schema\\\/person\\\/6b4869f122ec229aca6c597b8b59f661\"},\"headline\":\"Pratiche in classe che creano connessione\",\"datePublished\":\"2020-11-19T00:50:20+00:00\",\"dateModified\":\"2025-06-10T22:50:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/\"},\"wordCount\":3123,\"publisher\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/#\\\/schema\\\/person\\\/6b4869f122ec229aca6c597b8b59f661\"},\"image\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Classpracticesrsv2.jpg\",\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/\",\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/\",\"name\":\"Pratiche in classe che creano connessione - Positive Discipline in the Montessori Classroom\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Classpracticesrsv2.jpg\",\"datePublished\":\"2020-11-19T00:50:20+00:00\",\"dateModified\":\"2025-06-10T22:50:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Classpracticesrsv2.jpg\",\"contentUrl\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2020\\\/11\\\/Classpracticesrsv2.jpg\",\"width\":1172,\"height\":581},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/pratiche-in-classe-che-creano-connessione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/homepage-del-cd\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pratiche in classe che creano connessione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/\",\"name\":\"Positive Discipline in the Montessori Classroom\",\"description\":\"Positive Discipline training for Montessori educators\",\"publisher\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/#\\\/schema\\\/person\\\/6b4869f122ec229aca6c597b8b59f661\"},\"alternateName\":\"PDMC Montessori\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/#\\\/schema\\\/person\\\/6b4869f122ec229aca6c597b8b59f661\",\"name\":\"Chip DeLorenzo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-PDMC-Website-Logo-1-1.png\",\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-PDMC-Website-Logo-1-1.png\",\"contentUrl\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-PDMC-Website-Logo-1-1.png\",\"width\":1554,\"height\":395,\"caption\":\"Chip DeLorenzo\"},\"logo\":{\"@id\":\"https:\\\/\\\/pdmc-montessori.org\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/cropped-PDMC-Website-Logo-1-1.png\"},\"url\":\"https:\\\/\\\/pdmc-montessori.org\\\/it\\\/author\\\/chipdauthor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pratiche in classe che creano connessione - Positive Discipline in the Montessori Classroom","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/","og_locale":"it_IT","og_type":"article","og_title":"Pratiche in classe che creano connessione - Positive Discipline in the Montessori Classroom","og_description":"1. Coinvolgere i bambini nella creazione di regole di base e routine Le routine danno ai bambini l&#8217;opportunit\u00e0 di prevedere cosa accadr\u00e0 dopo. Quando i bambini sono in grado di prevedere cosa accadr\u00e0 dopo, hanno [&hellip;]","og_url":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/","og_site_name":"Positive Discipline in the Montessori Classroom","article_published_time":"2020-11-19T00:50:20+00:00","article_modified_time":"2025-06-10T22:50:28+00:00","og_image":[{"width":1172,"height":581,"url":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2020\/11\/Classpracticesrsv2.jpg","type":"image\/jpeg"}],"author":"Chip DeLorenzo","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Chip DeLorenzo","Est. reading time":"15 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/#article","isPartOf":{"@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/"},"author":{"name":"Chip DeLorenzo","@id":"https:\/\/pdmc-montessori.org\/it\/#\/schema\/person\/6b4869f122ec229aca6c597b8b59f661"},"headline":"Pratiche in classe che creano connessione","datePublished":"2020-11-19T00:50:20+00:00","dateModified":"2025-06-10T22:50:28+00:00","mainEntityOfPage":{"@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/"},"wordCount":3123,"publisher":{"@id":"https:\/\/pdmc-montessori.org\/it\/#\/schema\/person\/6b4869f122ec229aca6c597b8b59f661"},"image":{"@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/#primaryimage"},"thumbnailUrl":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2020\/11\/Classpracticesrsv2.jpg","inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/","url":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/","name":"Pratiche in classe che creano connessione - Positive Discipline in the Montessori Classroom","isPartOf":{"@id":"https:\/\/pdmc-montessori.org\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/#primaryimage"},"image":{"@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/#primaryimage"},"thumbnailUrl":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2020\/11\/Classpracticesrsv2.jpg","datePublished":"2020-11-19T00:50:20+00:00","dateModified":"2025-06-10T22:50:28+00:00","breadcrumb":{"@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/#primaryimage","url":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2020\/11\/Classpracticesrsv2.jpg","contentUrl":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2020\/11\/Classpracticesrsv2.jpg","width":1172,"height":581},{"@type":"BreadcrumbList","@id":"https:\/\/pdmc-montessori.org\/it\/pratiche-in-classe-che-creano-connessione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/pdmc-montessori.org\/it\/homepage-del-cd\/"},{"@type":"ListItem","position":2,"name":"Pratiche in classe che creano connessione"}]},{"@type":"WebSite","@id":"https:\/\/pdmc-montessori.org\/it\/#website","url":"https:\/\/pdmc-montessori.org\/it\/","name":"Positive Discipline in the Montessori Classroom","description":"Positive Discipline training for Montessori educators","publisher":{"@id":"https:\/\/pdmc-montessori.org\/it\/#\/schema\/person\/6b4869f122ec229aca6c597b8b59f661"},"alternateName":"PDMC Montessori","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pdmc-montessori.org\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Person","Organization"],"@id":"https:\/\/pdmc-montessori.org\/it\/#\/schema\/person\/6b4869f122ec229aca6c597b8b59f661","name":"Chip DeLorenzo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2025\/03\/cropped-PDMC-Website-Logo-1-1.png","url":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2025\/03\/cropped-PDMC-Website-Logo-1-1.png","contentUrl":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2025\/03\/cropped-PDMC-Website-Logo-1-1.png","width":1554,"height":395,"caption":"Chip DeLorenzo"},"logo":{"@id":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2025\/03\/cropped-PDMC-Website-Logo-1-1.png"},"url":"https:\/\/pdmc-montessori.org\/it\/author\/chipdauthor\/"}]}},"jetpack_featured_media_url":"https:\/\/pdmc-montessori.org\/wp-content\/uploads\/2020\/11\/Classpracticesrsv2.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/posts\/10691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/comments?post=10691"}],"version-history":[{"count":0,"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/posts\/10691\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/media\/5969"}],"wp:attachment":[{"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/media?parent=10691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/categories?post=10691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pdmc-montessori.org\/it\/wp-json\/wp\/v2\/tags?post=10691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}